{"id":88,"date":"2026-04-27T13:06:22","date_gmt":"2026-04-27T13:06:22","guid":{"rendered":"https:\/\/act-ing.fr\/?p=88"},"modified":"2026-05-04T11:01:18","modified_gmt":"2026-05-04T11:01:18","slug":"cartographie-des-travaux-du-programme-de-recherche-cours-daction","status":"publish","type":"post","link":"https:\/\/act-ing.fr\/index.php\/2026\/04\/27\/cartographie-des-travaux-du-programme-de-recherche-cours-daction\/","title":{"rendered":"Cartographie des travaux du programme de recherche cours d&rsquo;action"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un questionnaire est en cours de construction pour permettre la cr\u00e9ation d&rsquo;une cartographie des travaux du programme de recherche du cours d&rsquo;action<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un questionnaire est en cours de construction pour permettre la cr\u00e9ation d&rsquo;une cartographie des travaux du programme de recherche du cours d&rsquo;action<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","footnotes":""},"categories":[9],"tags":[],"class_list":["post-88","post","type-post","status-publish","format-standard","hentry","category-projets-en-cours"],"_links":{"self":[{"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/posts\/88","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/comments?post=88"}],"version-history":[{"count":2,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/posts\/88\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/posts\/88\/revisions\/126"}],"wp:attachment":[{"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/media?parent=88"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/categories?post=88"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/act-ing.fr\/index.php\/wp-json\/wp\/v2\/tags?post=88"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}